{"id":5635,"date":"2024-06-15T00:20:50","date_gmt":"2024-06-14T21:20:50","guid":{"rendered":"https:\/\/theologos-guide.gr\/place\/taverna-ostria-skala-atalanti-greece\/"},"modified":"2024-06-15T00:20:50","modified_gmt":"2024-06-14T21:20:50","slug":"taverna-ostria-skala-atalanti-greece","status":"publish","type":"listing","link":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/","title":{"rendered":"Taverna Ostria, Skala Atalanti, Greece"},"content":{"rendered":"\n<p>Soon more information about Taverna Ostria in Atalanti Beach in Atalanti.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soon more information about Taverna Ostria in Atalanti Beach in Atalanti.<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"listing_location":[268],"listing_cat":[303,591],"listing_tag":[],"class_list":["post-5635","listing","type-listing","status-publish","hentry","listing_location-skala-atalanti-fthiotida","listing_cat-food","listing_cat-restaurants-taverns-atalanti-fthiotida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taverna Ostria, Skala Atalanti, Greece - Theologos Guide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taverna Ostria, Skala Atalanti, Greece - Theologos Guide\" \/>\n<meta property=\"og:description\" content=\"Soon more information about Taverna Ostria in Atalanti Beach in Atalanti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/\" \/>\n<meta property=\"og:site_name\" content=\"Theologos Guide\" \/>\n<meta property=\"og:image\" content=\"https:\/\/theologos-guide.gr\/wp-content\/uploads\/2019\/08\/taverna-ostria-skala-atalantis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/\",\"url\":\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/\",\"name\":\"Taverna Ostria, Skala Atalanti, Greece - Theologos Guide\",\"isPartOf\":{\"@id\":\"https:\/\/theologos-guide.gr\/#website\"},\"datePublished\":\"2024-06-14T21:20:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/theologos-guide.gr\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listings\",\"item\":\"https:\/\/theologos-guide.gr\/place\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taverna Ostria, Skala Atalanti, Greece\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/theologos-guide.gr\/#website\",\"url\":\"https:\/\/theologos-guide.gr\/\",\"name\":\"Theologos Guide\",\"description\":\"Theologos Fthiotida Tourist Guide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/theologos-guide.gr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taverna Ostria, Skala Atalanti, Greece - Theologos Guide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/","og_locale":"en_US","og_type":"article","og_title":"Taverna Ostria, Skala Atalanti, Greece - Theologos Guide","og_description":"Soon more information about Taverna Ostria in Atalanti Beach in Atalanti.","og_url":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/","og_site_name":"Theologos Guide","og_image":[{"width":1200,"height":675,"url":"https:\/\/theologos-guide.gr\/wp-content\/uploads\/2019\/08\/taverna-ostria-skala-atalantis.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/","url":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/","name":"Taverna Ostria, Skala Atalanti, Greece - Theologos Guide","isPartOf":{"@id":"https:\/\/theologos-guide.gr\/#website"},"datePublished":"2024-06-14T21:20:50+00:00","breadcrumb":{"@id":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/theologos-guide.gr\/en\/place\/taverna-ostria-skala-atalanti-greece\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/theologos-guide.gr\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Listings","item":"https:\/\/theologos-guide.gr\/place\/"},{"@type":"ListItem","position":3,"name":"Taverna Ostria, Skala Atalanti, Greece"}]},{"@type":"WebSite","@id":"https:\/\/theologos-guide.gr\/#website","url":"https:\/\/theologos-guide.gr\/","name":"Theologos Guide","description":"Theologos Fthiotida Tourist Guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/theologos-guide.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/listings\/5635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/listings"}],"about":[{"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/comments?post=5635"}],"wp:attachment":[{"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/media?parent=5635"}],"wp:term":[{"taxonomy":"listing_location","embeddable":true,"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/listing_location?post=5635"},{"taxonomy":"listing_cat","embeddable":true,"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/listing_cat?post=5635"},{"taxonomy":"listing_tag","embeddable":true,"href":"https:\/\/theologos-guide.gr\/en\/wp-json\/wp\/v2\/listing_tag?post=5635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}